{"id":18252,"date":"2022-04-06T15:19:24","date_gmt":"2022-04-06T13:19:24","guid":{"rendered":"https:\/\/www.munich-business-school.de\/insights\/?p=18252"},"modified":"2023-07-03T10:48:12","modified_gmt":"2023-07-03T08:48:12","slug":"mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung","status":"publish","type":"post","link":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/","title":{"rendered":"MBS setzt als Partnerin im Verbundprojekt &#8222;Impact for Future&#8220; Impulse f\u00fcr verantwortungsbewusste Entrepreneurship-Ausbildung"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Die Munich Business School ist Teil der neu gef\u00f6rderten Initiative &#8222;Impact for Future&#8220;, die \u00fcber die n\u00e4chsten vier Jahre hinweg die Themen Impact und gesellschaftliche Verantwortung in der universit\u00e4ren Landschaft verankern m\u00f6chte.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Die &#8222;Qualifizierung von Studierenden, Wissenschaftlerinnen und Wissenschaftlern zu unternehmerisch verantwortungsvoll denkenden und handelnden Probleml\u00f6serinnen und Probleml\u00f6sern&#8220; ist in den Worten des bayrischen Wissenschaftsminister Bernd Sibler das Ziel der neuen F\u00f6rderma\u00dfnahme, von der auch die gemeinsame Initiative &#8222;Impact for Future&#8220; des M\u00fcnchner Partnerkonsortiums profitiert. Das M\u00fcnchner Partnerkonsortium besteht aus der <a href=\"https:\/\/www.tum.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Technischen Universit\u00e4t M\u00fcnchen<\/a>, der <a href=\"https:\/\/www.hm.edu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hochschule M\u00fcnchen<\/a>, der <a href=\"https:\/\/www.haw-landshut.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hochschule Landshut<\/a>, der <a href=\"https:\/\/www.munich-business-school.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Munich Business School (MBS)<\/a> sowie der <a href=\"https:\/\/www.unibw.de\/home\" target=\"_blank\" rel=\"noreferrer noopener\">Universit\u00e4t der Bundeswehr M\u00fcnchen<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Verbundprojekt &#8222;Impact for Future&#8220; kn\u00fcpft an die lange Tradition von Impact-orientiertem Entrepreneurship (IoE), das sich aus Sustainable und Social Entrepreneurship zusammensetzt, in M\u00fcnchen an und m\u00f6chte in den kommenden Jahren die L\u00fccke in der IoE-Ausbildung, die sich vor allem in der Beschr\u00e4nkung auf Studierende aus den Gesellschafts- und Sozialwissenschaften zeigt, schlie\u00dfen. Gemeinsam soll ein holistisches Lehrkonzept erarbeitet werden, dessen Angebote sich sowohl in der Breite als auch in der Spitze an unterschiedliche Zielgruppen &#8211; von Studierenden verschiedener Fachbereiche \u00fcber Lehrende und Mitarbeitende hin zu externen Akteur*innen &#8211; richten und ihren jeweiligen Bed\u00fcrfnissen gerecht werden. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Munich Business School bietet zahlreiche Best Practices zur Entwicklung eines Lehrkonzepts im Rahmen des &#8222;Impact for Future&#8220;-Projektes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Als assoziierte Hochschule wird sich die Munich Business School aktiv in die gemeinsame Initiative einbringen. Das Thema Impact ist \u00fcber die Hochschulwerte innovativ, verantwortungsbewusst und weltoffen fest in der DNA der Munich Business School verankert &#8211; erst Anfang des Jahres ver\u00f6ffentlichte die Hochschule ihren ersten <a href=\"https:\/\/www.munich-business-school.de\/insights\/2022\/munich-business-school-veroffentlicht-ersten-mbs-impact-report-zur-messung-gesellschaftlicher-wirkung-an-der-hochschule\/\">MBS Impact Report<\/a>, um auf die Verantwortung von Hochschulen f\u00fcr die Erzeugung eines gesellschaftlichen Mehrwerts aufmerksam zu machen. Dass Sustainable und Social Entrepreneurship wichtige Themenschwerpunkte der Munich Business School sind, zeigt sich insbesondere im <a href=\"https:\/\/www.munich-business-school.de\/master\/master-innovation-and-entrepreneurship\" target=\"_blank\" rel=\"noreferrer noopener\">Master Innovation and Entrepreneurship<\/a>. Hier belegen die Studierenden etwa verpflichtend den Kurs <em>Open &amp; Sustainable Innovation<\/em>, fokussieren sich bei der Ausarbeitung ihrer eigenen Gesch\u00e4ftsideen im Kurs <em>Resource Acquisition &amp; Business Planning<\/em> explizit auf Nachhaltigkeit und k\u00f6nnen im Wahlkurs <em>Understanding Social Start-ups<\/em> tiefer in soziales Unternehmertum eintauchen. Prof. Dr. Anne Tryba, Studiengangsleiterin des Masterprogramms und verantwortliche Mit-Koordinatorin der Initiative &#8222;Impact for Future&#8220; an der MBS, erg\u00e4nzt: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">&#8222;Auch in Seminar- und Abschlussarbeiten befassen sich die Studierenden vermehrt mit dem Themenkomplex und forschen beispielsweise zur nachhaltigen Gesch\u00e4ftsmodellumstellung in KMU.&#8220; <\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Aber auch abseits des Masters Innovation and Entrepreneurship finden sich im Bachelor-, Master- und MBA-Angebot der Munich Business School curriculare Elemente, bei denen die Impact-Fokussierung deutlich wird. Hier sind beispielsweise das Sozialprojekt mit einer gemeinn\u00fctzigen Organisation im MBS-Bachelor-Curriculum, der f\u00fcr alle Masterstudierenden verpflichtende Kurs <em>Conscious Business<\/em>, bei dem Unternehmertum als ganzheitliches Konstrukt inklusive der sozialen Aspekte betrachtet wird, sowie der Schwerpunkt auf Social Entrepreneurship im MBA Flagship Course <em>Entrepreneurship &amp; Innovation<\/em> zu nennen. Auf dem Gebiet der Forschung setzen sich die MBS-Professor*innen durch Mitwirkung bei den Forschungsprojekten <em>WEMag<\/em> (<em>Women Entrepreneurs in the Maghreb<\/em>), <em>EaSI<\/em> (<em>Technical Assistance for Social Finance Providers<\/em>) und <em>YES!<\/em> (<em>Young Entrepreneurs Succeed<\/em>) ebenfalls intensiv mit dem Thema Impact Entrepreneurship auseinander. Dar\u00fcber hinaus ist das einzigartige European Center for Social Finance (ECSF), geleitet von MBS-Professorin und Social-Entrepreneurship-Expertin Dr. Barbara Scheck, an der MBS ans\u00e4ssig. Diese und weitere Elemente werden in die Entwicklung des holistischen Lehrkonzept im Rahmen von &#8222;Impact for Future&#8220; einflie\u00dfen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Auftaktveranstaltung an der Munich Business School<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">&#8222;F\u00fcr uns als Hochschule ist die Beteiligung am Projekt \u201aImpact for Future\u2018 eine weitere M\u00f6glichkeit, uns noch st\u00e4rker im M\u00fcnchner Entrepreneurship Ecosystem zu vernetzen und selbst aktiv mitzuwirken. Wir freuen uns, durch das Konsortium unsere Schwerpunkte im Bereich Impact und Sustainable\/Social Entrepreneurship weiter auszubauen und Impulse f\u00fcr eine bayernweite Impact-orientierte Entrepreneurship-Ausbildung zu setzen.&#8220;, erl\u00e4utert Prof. Dr. Stefan Baldi, Dekan der Munich Business School, zum erfolgreichen Start des Projekts. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als eine erste Auftaktveranstaltung der &#8222;Impact for Future&#8220;-Initiative organisiert die Munich Business School am 28. April 2022 eine <a href=\"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-impact-pitch-night-business-ideen-mit-mehrwert-fuer-eine-bessere-zukunft\/\">Impact Pitch Ni<\/a><a href=\"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-impact-pitch-night-business-ideen-mit-mehrwert-fuer-eine-bessere-zukunft\/\" target=\"_blank\" rel=\"noreferrer noopener\">g<\/a><a href=\"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-impact-pitch-night-business-ideen-mit-mehrwert-fuer-eine-bessere-zukunft\/\">ht<\/a>, bei der die jeweils zwei besten nachhaltigen Businessideen aus den MBS-Entrepreneurship-Kursen im Bachelor, Master und MBA vor einer Jury vorgestellt und im Anschluss pr\u00e4miert werden. Nach den Pitches besteht die M\u00f6glichkeit zum Austausch mit G\u00e4sten und Partner*innen aus dem MBS Entrepreneurship Ecosystem. <\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.munich-business-school.de\/?mtm_campaign=Insights_Banner_Startseite-DE&amp;mtm_source=Blog&amp;mtm_medium=Banner-Blog\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2023\/06\/mbs-insights-billdbord-web-1.jpg\" alt=\"Banner &quot;Studiere Wirtschaft in M\u00fcnchen&quot;\" class=\"wp-image-20910\" style=\"width:1400px;height:236px\" width=\"1400\" height=\"236\" srcset=\"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2023\/06\/mbs-insights-billdbord-web-1.jpg 950w, https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2023\/06\/mbs-insights-billdbord-web-1-800x135.jpg 800w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/a><\/figure>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><br><strong>Du interessierst dich f\u00fcr Wirtschaft und m\u00f6chtest umfassendes Business Know-How erwerben?<\/strong><br>Dann sind die internationalen BWL-Studieng\u00e4nge an der Munich Business School (MBS) genau das Richtige f\u00fcr dich! An der MBS paukst du keine trockene Theorie aus alten Lehrb\u00fcchern, sondern lernst ergebnisorientiert und sammelst wertvolle praktische Erfahrungen. \u00dcberzeuge dich selbst:<br><br><a href=\"https:\/\/www.munich-business-school.de\/en\/bachelor\/bachelor-international-business?mtm_campaign=Insights_Banner_Bachelor-IB-DE&amp;mtm_source=Blog&amp;mtm_medium=Banner-Blog\">Bachelor International Business<\/a><br><a href=\"https:\/\/www.munich-business-school.de\/master\/master-international-business\/?mtm_campaign=Insights_Banner_Master-IB-DE&amp;mtm_source=Blog&amp;mtm_medium=Banner-Blog\">Master International Business<\/a><br><a href=\"https:\/\/www.munich-business-school.de\/master-bwl\/master-international-business-finance?mtm_campaign=Insights_Banner_Master-IB-Finance-DE&amp;mtm_source=Blog&amp;mtm_medium=Banner-Blog\">Master International Business I Finance<\/a><br><a href=\"https:\/\/www.munich-business-school.de\/en\/master\/master-innovation-and-entrepreneurship?mtm_campaign=Insights_Banner_Master-IE-DE&amp;mtm_source=Blog&amp;mtm_medium=Banner-Blog\">Master Innovation and Entrepreneurship<\/a><br><a href=\"https:\/\/www.munich-business-school.de\/master\/master-international-marketing-and-brand-management?mtm_campaign=Insights_Banner_Master-IMBM-DE&amp;mtm_source=Blog&amp;mtm_medium=Banner-Blog\">Master International Marketing and Brand Management<\/a><br><a href=\"https:\/\/www.munich-business-school.de\/master\/master-sports-business-and-communication\/?mtm_campaign=Insights_Banner_Master-SBC-DE&amp;mtm_source=Blog&amp;mtm_medium=Banner-Blog\">Master Sports Business and Communication<\/a><br><a href=\"https:\/\/www.munich-business-school.de\/mba\/mba-full-time?mtm_campaign=Insights_Banner_MBA-DE&amp;mtm_source=Blog&amp;mtm_medium=Banner-Blog\">MBA General Management<\/a><br><a href=\"https:\/\/www.munich-business-school.de\/dba?mtm_campaign=Insights_Banner_DBA-DE&amp;mtm_source=Blog&amp;mtm_medium=Banner-Blog\">Doctor of Business Administration<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Die Munich Business School ist Teil der neu gef\u00f6rderten Initiative &#8222;Impact for Future&#8220;, die \u00fcber die n\u00e4chsten vier Jahre hinweg die Themen Impact und gesellschaftliche Verantwortung in der universit\u00e4ren Landschaft verankern m\u00f6chte. Die &#8222;Qualifizierung von <a class=\"mh-excerpt-more\" href=\"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/\" title=\"MBS setzt als Partnerin im Verbundprojekt &#8222;Impact for Future&#8220; Impulse f\u00fcr verantwortungsbewusste Entrepreneurship-Ausbildung\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":26,"featured_media":18594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44,47,11990,51,5608,66,7138,2272,92,90,95,11,16,11986,100],"tags":[8844,255,7503,10593,10761,10779,10783,8496,11684,9971,2520,10767],"coauthors":[685],"class_list":["post-18252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bachelor-de","category-bachelor-international-business-de","category-campus-life","category-dba-de","category-homepage-de","category-innovation-entrepreneurship-de","category-master-innovation-and-entrepreneurship-de","category-mba-de","category-mba-general-management-full-time-de","category-mba-general-management-part-time-de","category-mbs-de","category-mbs-business-blog-de","category-mbs-news-de","category-news","category-soziale-verantwortung","tag-bachelor-international-business","tag-entrepreneurship-de","tag-european-center-for-social-finance","tag-impact-de","tag-impact-entrepreneurship","tag-impact-for-future","tag-konsortium","tag-master-innovation-and-entrepreneurship-de","tag-mba-general-management-de","tag-mba-general-management","tag-social-entrepreneurship-de","tag-sustainable-entrepreneurship-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u2713 MBS ist Partnerin im Verbundprojekt &quot;Impact for Future&quot;<\/title>\n<meta name=\"description\" content=\"Im Rahmen der Initiative &quot;Impact for Future&quot; setzt sich die Munich Business School f\u00fcr eine Entrepreneurship-Ausbildung mit Mehrwert ein.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2713 MBS ist Partnerin im Verbundprojekt &quot;Impact for Future&quot;\" \/>\n<meta property=\"og:description\" content=\"Im Rahmen der Initiative &quot;Impact for Future&quot; setzt sich die Munich Business School f\u00fcr eine Entrepreneurship-Ausbildung mit Mehrwert ein.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/\" \/>\n<meta property=\"og:site_name\" content=\"Munich Business School Insights\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Munich.Business.School\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-06T13:19:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-03T08:48:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2022\/03\/Impact-for-Future_Blog_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"690\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MBS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MunichBSchool\" \/>\n<meta name=\"twitter:site\" content=\"@MunichBSchool\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"MBS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"MBS\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/2022\\\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/2022\\\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\\\/\"},\"author\":{\"name\":\"MBS\",\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/#\\\/schema\\\/person\\\/69bdbdb2c808a1956492af2820a2a820\"},\"headline\":\"MBS setzt als Partnerin im Verbundprojekt &#8222;Impact for Future&#8220; Impulse f\u00fcr verantwortungsbewusste Entrepreneurship-Ausbildung\",\"datePublished\":\"2022-04-06T13:19:24+00:00\",\"dateModified\":\"2023-07-03T08:48:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/2022\\\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\\\/\"},\"wordCount\":731,\"publisher\":{\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/2022\\\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Impact-for-Future_Blog_1.jpg\",\"keywords\":[\"Bachelor International Business\",\"Entrepreneurship\",\"European Center for Social Finance\",\"Impact\",\"Impact Entrepreneurship\",\"Impact for Future\",\"Konsortium\",\"Master Innovation and Entrepreneurship\",\"MBA General Management\",\"MBA General Management\",\"Social Entrepreneurship\",\"Sustainable Entrepreneurship\"],\"articleSection\":[\"Bachelor\",\"Bachelor International Business\",\"Campus Life\",\"DBA\",\"Homepage DE\",\"Innovation &amp; Entrepreneurship\",\"Master Innovation and Entrepreneurship\",\"MBA\",\"MBA General Management Full-Time\",\"MBA General Management Part-Time\",\"MBS\",\"MBS Business Blog\",\"MBS News\",\"News\",\"Soziale Verantwortung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/2022\\\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\\\/\",\"url\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/2022\\\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\\\/\",\"name\":\"\u2713 MBS ist Partnerin im Verbundprojekt \\\"Impact for Future\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/2022\\\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/2022\\\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Impact-for-Future_Blog_1.jpg\",\"datePublished\":\"2022-04-06T13:19:24+00:00\",\"dateModified\":\"2023-07-03T08:48:12+00:00\",\"description\":\"Im Rahmen der Initiative \\\"Impact for Future\\\" setzt sich die Munich Business School f\u00fcr eine Entrepreneurship-Ausbildung mit Mehrwert ein.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/2022\\\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/2022\\\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/2022\\\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Impact-for-Future_Blog_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Impact-for-Future_Blog_1.jpg\",\"width\":1280,\"height\":690,\"caption\":\"Logo of Impact for Future Project, in which Munich Business School is a partner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/2022\\\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beitragsart\",\"item\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/category\\\/beitragsart\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MBS News\",\"item\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/category\\\/beitragsart\\\/mbs-news-de\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"MBS setzt als Partnerin im Verbundprojekt &#8222;Impact for Future&#8220; Impulse f\u00fcr verantwortungsbewusste Entrepreneurship-Ausbildung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/#website\",\"url\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/\",\"name\":\"Munich Business School Insights\",\"description\":\"Der Hochschulblog der Munich Business School: News zu Studium, Forschung, Lehre und Wirtschaft\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/#organization\",\"name\":\"Munich Business School\",\"url\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/b_MBS.png\",\"contentUrl\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/b_MBS.png\",\"width\":567,\"height\":288,\"caption\":\"Munich Business School\"},\"image\":{\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Munich.Business.School\\\/\",\"https:\\\/\\\/x.com\\\/MunichBSchool\",\"https:\\\/\\\/www.instagram.com\\\/munichbschool\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/388042\\\/\",\"https:\\\/\\\/www.youtube.com\\\/MunichBSchool\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/#\\\/schema\\\/person\\\/69bdbdb2c808a1956492af2820a2a820\",\"name\":\"MBS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-MBS-Munich-Business-School-Icon-96x96.png56172a01f644aa552b30b1fc7036db83\",\"url\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-MBS-Munich-Business-School-Icon-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-MBS-Munich-Business-School-Icon-96x96.png\",\"caption\":\"MBS\"},\"url\":\"https:\\\/\\\/www.munich-business-school.de\\\/insights\\\/author\\\/mbs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2713 MBS ist Partnerin im Verbundprojekt \"Impact for Future\"","description":"Im Rahmen der Initiative \"Impact for Future\" setzt sich die Munich Business School f\u00fcr eine Entrepreneurship-Ausbildung mit Mehrwert ein.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/","og_locale":"de_DE","og_type":"article","og_title":"\u2713 MBS ist Partnerin im Verbundprojekt \"Impact for Future\"","og_description":"Im Rahmen der Initiative \"Impact for Future\" setzt sich die Munich Business School f\u00fcr eine Entrepreneurship-Ausbildung mit Mehrwert ein.","og_url":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/","og_site_name":"Munich Business School Insights","article_publisher":"https:\/\/www.facebook.com\/Munich.Business.School\/","article_published_time":"2022-04-06T13:19:24+00:00","article_modified_time":"2023-07-03T08:48:12+00:00","og_image":[{"width":1280,"height":690,"url":"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2022\/03\/Impact-for-Future_Blog_1.jpg","type":"image\/jpeg"}],"author":"MBS","twitter_card":"summary_large_image","twitter_creator":"@MunichBSchool","twitter_site":"@MunichBSchool","twitter_misc":{"Verfasst von":"MBS","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten","Written by":"MBS"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/#article","isPartOf":{"@id":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/"},"author":{"name":"MBS","@id":"https:\/\/www.munich-business-school.de\/insights\/#\/schema\/person\/69bdbdb2c808a1956492af2820a2a820"},"headline":"MBS setzt als Partnerin im Verbundprojekt &#8222;Impact for Future&#8220; Impulse f\u00fcr verantwortungsbewusste Entrepreneurship-Ausbildung","datePublished":"2022-04-06T13:19:24+00:00","dateModified":"2023-07-03T08:48:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/"},"wordCount":731,"publisher":{"@id":"https:\/\/www.munich-business-school.de\/insights\/#organization"},"image":{"@id":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2022\/03\/Impact-for-Future_Blog_1.jpg","keywords":["Bachelor International Business","Entrepreneurship","European Center for Social Finance","Impact","Impact Entrepreneurship","Impact for Future","Konsortium","Master Innovation and Entrepreneurship","MBA General Management","MBA General Management","Social Entrepreneurship","Sustainable Entrepreneurship"],"articleSection":["Bachelor","Bachelor International Business","Campus Life","DBA","Homepage DE","Innovation &amp; Entrepreneurship","Master Innovation and Entrepreneurship","MBA","MBA General Management Full-Time","MBA General Management Part-Time","MBS","MBS Business Blog","MBS News","News","Soziale Verantwortung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/","url":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/","name":"\u2713 MBS ist Partnerin im Verbundprojekt \"Impact for Future\"","isPartOf":{"@id":"https:\/\/www.munich-business-school.de\/insights\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/#primaryimage"},"image":{"@id":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2022\/03\/Impact-for-Future_Blog_1.jpg","datePublished":"2022-04-06T13:19:24+00:00","dateModified":"2023-07-03T08:48:12+00:00","description":"Im Rahmen der Initiative \"Impact for Future\" setzt sich die Munich Business School f\u00fcr eine Entrepreneurship-Ausbildung mit Mehrwert ein.","breadcrumb":{"@id":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/#primaryimage","url":"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2022\/03\/Impact-for-Future_Blog_1.jpg","contentUrl":"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2022\/03\/Impact-for-Future_Blog_1.jpg","width":1280,"height":690,"caption":"Logo of Impact for Future Project, in which Munich Business School is a partner"},{"@type":"BreadcrumbList","@id":"https:\/\/www.munich-business-school.de\/insights\/2022\/mbs-setzt-als-partnerin-im-verbundprojekt-impact-for-future-impulse-fuer-verantwortungsbewusste-entrepreneurship-ausbildung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.munich-business-school.de\/insights\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Beitragsart","item":"https:\/\/www.munich-business-school.de\/insights\/category\/beitragsart\/"},{"@type":"ListItem","position":3,"name":"MBS News","item":"https:\/\/www.munich-business-school.de\/insights\/category\/beitragsart\/mbs-news-de\/"},{"@type":"ListItem","position":4,"name":"MBS setzt als Partnerin im Verbundprojekt &#8222;Impact for Future&#8220; Impulse f\u00fcr verantwortungsbewusste Entrepreneurship-Ausbildung"}]},{"@type":"WebSite","@id":"https:\/\/www.munich-business-school.de\/insights\/#website","url":"https:\/\/www.munich-business-school.de\/insights\/","name":"Munich Business School Insights","description":"Der Hochschulblog der Munich Business School: News zu Studium, Forschung, Lehre und Wirtschaft","publisher":{"@id":"https:\/\/www.munich-business-school.de\/insights\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.munich-business-school.de\/insights\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.munich-business-school.de\/insights\/#organization","name":"Munich Business School","url":"https:\/\/www.munich-business-school.de\/insights\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.munich-business-school.de\/insights\/#\/schema\/logo\/image\/","url":"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2018\/02\/b_MBS.png","contentUrl":"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2018\/02\/b_MBS.png","width":567,"height":288,"caption":"Munich Business School"},"image":{"@id":"https:\/\/www.munich-business-school.de\/insights\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Munich.Business.School\/","https:\/\/x.com\/MunichBSchool","https:\/\/www.instagram.com\/munichbschool\/","https:\/\/www.linkedin.com\/school\/388042\/","https:\/\/www.youtube.com\/MunichBSchool"]},{"@type":"Person","@id":"https:\/\/www.munich-business-school.de\/insights\/#\/schema\/person\/69bdbdb2c808a1956492af2820a2a820","name":"MBS","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2024\/11\/cropped-MBS-Munich-Business-School-Icon-96x96.png56172a01f644aa552b30b1fc7036db83","url":"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2024\/11\/cropped-MBS-Munich-Business-School-Icon-96x96.png","contentUrl":"https:\/\/www.munich-business-school.de\/insights\/wp-content\/uploads\/2024\/11\/cropped-MBS-Munich-Business-School-Icon-96x96.png","caption":"MBS"},"url":"https:\/\/www.munich-business-school.de\/insights\/author\/mbs\/"}]}},"_links":{"self":[{"href":"https:\/\/www.munich-business-school.de\/insights\/wp-json\/wp\/v2\/posts\/18252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.munich-business-school.de\/insights\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.munich-business-school.de\/insights\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.munich-business-school.de\/insights\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.munich-business-school.de\/insights\/wp-json\/wp\/v2\/comments?post=18252"}],"version-history":[{"count":15,"href":"https:\/\/www.munich-business-school.de\/insights\/wp-json\/wp\/v2\/posts\/18252\/revisions"}],"predecessor-version":[{"id":21262,"href":"https:\/\/www.munich-business-school.de\/insights\/wp-json\/wp\/v2\/posts\/18252\/revisions\/21262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.munich-business-school.de\/insights\/wp-json\/wp\/v2\/media\/18594"}],"wp:attachment":[{"href":"https:\/\/www.munich-business-school.de\/insights\/wp-json\/wp\/v2\/media?parent=18252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.munich-business-school.de\/insights\/wp-json\/wp\/v2\/categories?post=18252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.munich-business-school.de\/insights\/wp-json\/wp\/v2\/tags?post=18252"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.munich-business-school.de\/insights\/wp-json\/wp\/v2\/coauthors?post=18252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}